{"id":11221,"date":"2026-05-13T10:52:38","date_gmt":"2026-05-13T08:52:38","guid":{"rendered":"https:\/\/erhardt-stiefel.de\/?p=11221"},"modified":"2026-05-13T10:52:38","modified_gmt":"2026-05-13T08:52:38","slug":"fuer-gebet-gibt-es-keinen-ersatz-2","status":"publish","type":"post","link":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/","title":{"rendered":"F\u00fcr Gebet gibt es keinen Ersatz"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4814\" src=\"https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13.jpg\" alt=\"\" width=\"790\" height=\"887\" srcset=\"https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13.jpg 790w, https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13-267x300.jpg 267w, https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13-768x862.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p><strong>Da sie das h\u00f6rten, erhoben sie einm\u00fctig ihre Stimme zu Gott und sprachen&#8230; und da sie so gebetet hatten, erbebte die St\u00e4tte, da sie versammelt waren; und sie wurden alle des Heiligen Geistes voll und redeten das Wort Gottes mit Freiheit. <a href=\"https:\/\/www.bibleserver.com\/LUT\/Apostelgeschichte4%2C24.31\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><span style=\"color: #0000ff;\">Apostelgeschichte 4, 24+31<\/span><\/a><\/strong><\/p>\n<p>&nbsp;\u201eNur Gebetsstunde\u201c \u2013 wie oft habe ich diesen Ausspruch geh\u00f6rt, und dabei in gelangweilte Gesichter geschaut. \u201eWir haben unsere Gebetsstunden abgeschafft,\u201c sagte mir der Pastor. \u201eEs finden einfach zu viele Aktivit\u00e4ten statt und beten kann man auch zu Hause oder im Hauskreis.\u201c Dann erlebte ich zum Abschluss des Seminars noch den Gottesdienst am Sonntagmorgen. Etwa eine Stunde wurde stehend gesungen und mir taten die Beine weh; wie gerne h\u00e4tte ich mich gesetzt, aber wer hat schon den Mut dazu, wenn doch alle stehend singen. Also blieb auch ich stehen. Sehns\u00fcchtig wartete ich, dass gebetet w\u00fcrde, aber schon begann die Predigt.&nbsp; Auf bescheidenes Hinterfragen erhielt ich die Antwort, dass die gesungenen Lieder ja bereits schon Gebete waren, warum noch zus\u00e4tzlich Gebete sprechen, zumal die Besucher das nicht verstehen w\u00fcrden.<!--more--><\/p>\n<p>Im Geist ging ich nach Jerusalem. Ich wollte an einer richtigen Gebetsstunde teilnehmen. Welch eine Atmosph\u00e4re! Es m\u00fcssen etwa 5000 gewesen sein, die sich hier versammelt hatten. Die Predigt bestand nur aus einer kurzen Mitteilung: \u201eNiemand darf den Namen Jesu mehr \u00f6ffentlich bekennen. Wollen wir das hinnehmen?\u201c \u201eNiemals\u201c, schrien die Anwesenden. \u201eWas gedenkt ihr zu tun?\u201c \u201eDas werden wir hier und heute \u00e4ndern! Wir werden den Himmel best\u00fcrmen und Gott um Rat und Beistand bitten. Das Evangelium darf nicht gestoppt werden!\u201c &#8211; und schon erhob sich die Gemeinde, und mit lauter Stimme traten sie vor Gott und begannen inbr\u00fcnstig zu beten. Der Erfolg lie\u00df nicht lange auf sich warten. Alle wurden mit dem Heiligen Geist erf\u00fcllt und jeder konnte innerlich gest\u00e4rkt mutig auf die Stra\u00dfe gehen und weitergeben, was Gott an ihm getan hatte, und die Zahl der Gl\u00e4ubigen nahm t\u00e4glich zu.<\/p>\n<p>Ob das nur in Jerusalem so war? Studieren wir geistliche Aufbr\u00fcche, entdecken wir, dass das Gebet in den Gottesdiensten eine viel gr\u00f6\u00dfere Rolle spielte, als mein Pastor es mir zu erkl\u00e4ren versuchte. Gemeinsames Gebet hat eine gro\u00dfartige Verhei\u00dfung: Jesus sagt: <em>Wenn zwei unter euch eins werden auf Erden, worum sie bitten wollen, das soll ihnen widerfahren von meinem Vater im Himmel.<\/em>&nbsp; <a href=\"https:\/\/www.bibleserver.com\/LUT\/Matth%C3%A4us18%2C19\" target=\"_blank\" rel=\"noopener noreferrer nofollow\"><span style=\"color: #0000ff;\">Matth. 18, 19<\/span><\/a>.<\/p>\n<p>Darum gibt es \u00fcberall auf der Welt Gottesdienste, wo das gemeinsame Gebet seinen geb\u00fchrenden Platz hat. Man ruft die Kranken, die M\u00fchseligen und Beladenen und die Gemeinde stellt sich geschlossen hinter sie und bittet Gott um Sein Eingreifen und es geschehen Zeichen und Wunder. Das erleben die Besucher und sie m\u00fcssen erkennen, dass Gott wirklich anwesend ist. Das wiederum spricht sich herum, und schon kommt es zu geistlichen Aufbr\u00fcchen. Wer betet, gleicht dem Hohepriester, der zw\u00f6lf Edelsteine auf dem Brustschild trug, welches fest auf sein Herz gebunden war, und diese vor Gott brachte, wenn er in das Heiligtum eintrat. Diese zw\u00f6lf Steine symbolisierten das Volk Israel.<\/p>\n<p>Christenmenschen sind ein Volk von K\u00f6nigen und Priestern und Gott sucht Priester, die dasselbe tun. Wer sich nach geistlichen Aufbr\u00fcchen sehnt, muss daf\u00fcr sorgen, dass die Gl\u00e4ubigen ihre Berufung erkennen.. Gemeinsam werden Festungen erst\u00fcrmt und Gefangene befreit und der Heilige Geist bekommt die Gelegenheit, jeden mit Vollmacht auszur\u00fcsten. Ein Gottesdienst, der nur aus Gesang, Predigt und Bekanntmachung besteht ist kein Gottesdienst im Vollsinn. Erst der, der betet, dient Gott, und wenn alle mit einstimmen, ist das ein Gottesdienst.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da sie das h\u00f6rten, erhoben sie einm\u00fctig ihre Stimme zu Gott und sprachen&#8230; und da sie so gebetet hatten, erbebte die St\u00e4tte, da sie versammelt waren; und sie wurden alle des Heiligen Geistes voll und redeten das Wort Gottes mit Freiheit. Apostelgeschichte 4, 24+31 &nbsp;\u201eNur Gebetsstunde\u201c \u2013 wie oft habe ich diesen Ausspruch geh\u00f6rt, und &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eF\u00fcr Gebet gibt es keinen Ersatz\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[319,311],"tags":[317,329,387],"class_list":["post-11221","post","type-post","status-publish","format-standard","hentry","category-adlerbotschaft","category-predigten","tag-adler","tag-apostelgeschichte","tag-mai"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00fcr Gebet gibt es keinen Ersatz - Erhardt Stiefel&#039;s Fundgrube<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fcr Gebet gibt es keinen Ersatz - Erhardt Stiefel&#039;s Fundgrube\" \/>\n<meta property=\"og:description\" content=\"Da sie das h\u00f6rten, erhoben sie einm\u00fctig ihre Stimme zu Gott und sprachen&#8230; und da sie so gebetet hatten, erbebte die St\u00e4tte, da sie versammelt waren; und sie wurden alle des Heiligen Geistes voll und redeten das Wort Gottes mit Freiheit. Apostelgeschichte 4, 24+31 &nbsp;\u201eNur Gebetsstunde\u201c \u2013 wie oft habe ich diesen Ausspruch geh\u00f6rt, und &hellip; \u201eF\u00fcr Gebet gibt es keinen Ersatz\u201c weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Erhardt Stiefel&#039;s Fundgrube\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T08:52:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"790\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Erhardt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@erhardtstiefel77\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erhardt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/\"},\"author\":{\"name\":\"Erhardt\",\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/#\\\/schema\\\/person\\\/623af879bb14c4ae6622ece81ec006ef\"},\"headline\":\"F\u00fcr Gebet gibt es keinen Ersatz\",\"datePublished\":\"2026-05-13T08:52:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/\"},\"wordCount\":602,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erhardt-stiefel.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/13.jpg\",\"keywords\":[\"Adler\",\"Apostelgeschichte\",\"Mai\"],\"articleSection\":[\"Adlerbotschaft\",\"Predigten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/\",\"url\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/\",\"name\":\"F\u00fcr Gebet gibt es keinen Ersatz - Erhardt Stiefel&#039;s Fundgrube\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/erhardt-stiefel.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/13.jpg\",\"datePublished\":\"2026-05-13T08:52:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/#\\\/schema\\\/person\\\/623af879bb14c4ae6622ece81ec006ef\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/erhardt-stiefel.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/13.jpg\",\"contentUrl\":\"https:\\\/\\\/erhardt-stiefel.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/13.jpg\",\"width\":790,\"height\":887},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/2026\\\/05\\\/13\\\/fuer-gebet-gibt-es-keinen-ersatz-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/erhardt-stiefel.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00fcr Gebet gibt es keinen Ersatz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/#website\",\"url\":\"https:\\\/\\\/erhardt-stiefel.de\\\/\",\"name\":\"Erhardt Stiefel&#039;s Fundgrube\",\"description\":\"Erfahrungen mit CMS, Genealogie, Gott und der Welt - die ich sehr gerne mit dir teilen w\u00fcrde\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/erhardt-stiefel.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/erhardt-stiefel.de\\\/#\\\/schema\\\/person\\\/623af879bb14c4ae6622ece81ec006ef\",\"name\":\"Erhardt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086c9cb068fa330c15ed0aabfea0b66ecfa387fd1d6eb1a1a3b0a963becd7f74?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086c9cb068fa330c15ed0aabfea0b66ecfa387fd1d6eb1a1a3b0a963becd7f74?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/086c9cb068fa330c15ed0aabfea0b66ecfa387fd1d6eb1a1a3b0a963becd7f74?s=96&d=mm&r=g\",\"caption\":\"Erhardt\"},\"sameAs\":[\"https:\\\/\\\/erhardt-stiefel.de\",\"https:\\\/\\\/x.com\\\/erhardtstiefel77\"],\"url\":\"https:\\\/\\\/erhardt-stiefel.de\\\/index.php\\\/author\\\/erhardt_stiefel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00fcr Gebet gibt es keinen Ersatz - Erhardt Stiefel&#039;s Fundgrube","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/","og_locale":"de_DE","og_type":"article","og_title":"F\u00fcr Gebet gibt es keinen Ersatz - Erhardt Stiefel&#039;s Fundgrube","og_description":"Da sie das h\u00f6rten, erhoben sie einm\u00fctig ihre Stimme zu Gott und sprachen&#8230; und da sie so gebetet hatten, erbebte die St\u00e4tte, da sie versammelt waren; und sie wurden alle des Heiligen Geistes voll und redeten das Wort Gottes mit Freiheit. Apostelgeschichte 4, 24+31 &nbsp;\u201eNur Gebetsstunde\u201c \u2013 wie oft habe ich diesen Ausspruch geh\u00f6rt, und &hellip; \u201eF\u00fcr Gebet gibt es keinen Ersatz\u201c weiterlesen","og_url":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/","og_site_name":"Erhardt Stiefel&#039;s Fundgrube","article_published_time":"2026-05-13T08:52:38+00:00","og_image":[{"width":790,"height":887,"url":"https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13.jpg","type":"image\/jpeg"}],"author":"Erhardt","twitter_card":"summary_large_image","twitter_creator":"@erhardtstiefel77","twitter_misc":{"Geschrieben von":"Erhardt","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/#article","isPartOf":{"@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/"},"author":{"name":"Erhardt","@id":"https:\/\/erhardt-stiefel.de\/#\/schema\/person\/623af879bb14c4ae6622ece81ec006ef"},"headline":"F\u00fcr Gebet gibt es keinen Ersatz","datePublished":"2026-05-13T08:52:38+00:00","mainEntityOfPage":{"@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/"},"wordCount":602,"commentCount":0,"image":{"@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/#primaryimage"},"thumbnailUrl":"https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13.jpg","keywords":["Adler","Apostelgeschichte","Mai"],"articleSection":["Adlerbotschaft","Predigten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/","url":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/","name":"F\u00fcr Gebet gibt es keinen Ersatz - Erhardt Stiefel&#039;s Fundgrube","isPartOf":{"@id":"https:\/\/erhardt-stiefel.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/#primaryimage"},"image":{"@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/#primaryimage"},"thumbnailUrl":"https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13.jpg","datePublished":"2026-05-13T08:52:38+00:00","author":{"@id":"https:\/\/erhardt-stiefel.de\/#\/schema\/person\/623af879bb14c4ae6622ece81ec006ef"},"breadcrumb":{"@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/#primaryimage","url":"https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13.jpg","contentUrl":"https:\/\/erhardt-stiefel.de\/wp-content\/uploads\/2021\/05\/13.jpg","width":790,"height":887},{"@type":"BreadcrumbList","@id":"https:\/\/erhardt-stiefel.de\/index.php\/2026\/05\/13\/fuer-gebet-gibt-es-keinen-ersatz-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/erhardt-stiefel.de\/"},{"@type":"ListItem","position":2,"name":"F\u00fcr Gebet gibt es keinen Ersatz"}]},{"@type":"WebSite","@id":"https:\/\/erhardt-stiefel.de\/#website","url":"https:\/\/erhardt-stiefel.de\/","name":"Erhardt Stiefel&#039;s Fundgrube","description":"Erfahrungen mit CMS, Genealogie, Gott und der Welt - die ich sehr gerne mit dir teilen w\u00fcrde","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/erhardt-stiefel.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/erhardt-stiefel.de\/#\/schema\/person\/623af879bb14c4ae6622ece81ec006ef","name":"Erhardt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/086c9cb068fa330c15ed0aabfea0b66ecfa387fd1d6eb1a1a3b0a963becd7f74?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/086c9cb068fa330c15ed0aabfea0b66ecfa387fd1d6eb1a1a3b0a963becd7f74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/086c9cb068fa330c15ed0aabfea0b66ecfa387fd1d6eb1a1a3b0a963becd7f74?s=96&d=mm&r=g","caption":"Erhardt"},"sameAs":["https:\/\/erhardt-stiefel.de","https:\/\/x.com\/erhardtstiefel77"],"url":"https:\/\/erhardt-stiefel.de\/index.php\/author\/erhardt_stiefel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paRlFh-2UZ","_links":{"self":[{"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/posts\/11221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/comments?post=11221"}],"version-history":[{"count":1,"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/posts\/11221\/revisions"}],"predecessor-version":[{"id":11222,"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/posts\/11221\/revisions\/11222"}],"wp:attachment":[{"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/media?parent=11221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/categories?post=11221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/erhardt-stiefel.de\/index.php\/wp-json\/wp\/v2\/tags?post=11221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}